{"id":18698,"date":"2024-09-25T13:33:20","date_gmt":"2024-09-25T11:33:20","guid":{"rendered":"https:\/\/nele-stroebel.de\/?p=18698"},"modified":"2024-10-05T16:44:08","modified_gmt":"2024-10-05T14:44:08","slug":"black-whole-leporello-13","status":"publish","type":"post","link":"https:\/\/nele-stroebel.de\/fr\/black-whole-leporello-13\/","title":{"rendered":"couleurs dans le ciel"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"18698\" class=\"elementor elementor-18698 elementor-18695\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bea083d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bea083d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf456c9\" data-id=\"cf456c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-605af68 elementor-widget elementor-widget-elementskit-simple-tab\" data-id=\"605af68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-simple-tab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <div class=\"elementkit-tab-wraper   elementskit-fitcontent-tab \">\n            <ul class=\"nav nav-tabs elementkit-tab-nav \" role=\"tablist\">\n                                    <li class=\"elementkit-nav-item elementor-repeater-item-d53560e\" role=\"presentation\">\n                        <a class=\"elementkit-nav-link  active show left-pos\" id=\"content-d53560e6a980fc1d088f-tab\" data-ekit-handler-id=\"info\" data-ekit-toggle=\"tab\" data-target=\"#content-d53560e6a980fc1d088f\" href=\"#Content-d53560e6a980fc1d088f\"\n                            data-ekit-toggle-trigger=\"click\"\n                            role=\"tab\" aria-controls=\"content-d53560e6a980fc1d088f\" aria-selected=\"true\">\n                            <span class=\"elementskit-tab-icon\"><i class=\"icon icon-earth\"><\/i><\/span>                            <span class=\"elementskit-tab-title\">\n                                Info                            <\/span>\n                        <\/a>\n                    <\/li>\n                                        <li class=\"elementkit-nav-item elementor-repeater-item-190a405\" role=\"presentation\">\n                        <a class=\"elementkit-nav-link  left-pos\" id=\"content-190a4056a980fc1d088f-tab\" data-ekit-handler-id=\"images\" data-ekit-toggle=\"tab\" data-target=\"#content-190a4056a980fc1d088f\" href=\"#Content-190a4056a980fc1d088f\"\n                            data-ekit-toggle-trigger=\"click\"\n                            role=\"tab\" aria-controls=\"content-190a4056a980fc1d088f\" aria-selected=\"false\">\n                            <span class=\"elementskit-tab-icon\"><i class=\"icon icon-earth\"><\/i><\/span>                            <span class=\"elementskit-tab-title\">\n                                Images                            <\/span>\n                        <\/a>\n                    <\/li>\n                                <\/ul>\n\n            <div class=\"tab-content elementkit-tab-content\">\n                                    <div class=\"tab-pane elementkit-tab-pane elementor-repeater-item-d53560e  active show\" id=\"content-d53560e6a980fc1d088f\" role=\"tabpanel\"\n                         aria-labelledby=\"content-d53560e6a980fc1d088f-tab\" tabindex=\"0\">\n                        <div class=\"animated fadeIn\">\n                            <p>(n\u00e9on)couleurs dans le ciel<\/p>\n<p>Dans ce travail en deux parties, j&rsquo;aborde les nombreux \u00e9v\u00e9nements simultan\u00e9s et ambigus de cette \u00e9poque dystopique.<br \/>\nJ&rsquo;ai du mal \u00e0 en croire mes yeux.<br \/>\nQu&rsquo;est-ce qui est r\u00e9alit\u00e9, v\u00e9rit\u00e9, belles apparences ou ab\u00eeme de cruaut\u00e9 ?<br \/>\nDes drones militaires, d\u00e9guis\u00e9s en animaux tels que des hiboux ou des mouettes, ou ayant manifestement une apparence technique, sillonnent actuellement nos espaces a\u00e9riens et nos eaux.<br \/>\nIls sont en mission priv\u00e9e ou gouvernementale.<br \/>\nIls filment, tirent, espionnent et larguent des bombes.<br \/>\nT\u00e9l\u00e9guid\u00e9s, ils sont souvent invisibles.      <\/p>\n<p>Ce leporello parle d&rsquo;espaces architecturaux et int\u00e9rieurs qui ont perdu leur \u00e9quilibre.<br \/>\nIl est question d&rsquo;angoisses et de tentatives de comprendre et de g\u00e9rer l&rsquo;attraction des \u00e9v\u00e9nements. <\/p>\n<p>Les motifs de drones sont imprim\u00e9s au pochoir sur le papier, en blanc et en noir.<br \/>\nPar-dessus, des dessins au crayon de silhouettes de drones et de b\u00e2timents dans tous les \u00e9tats d&rsquo;agr\u00e9gation sont pos\u00e9s.<br \/>\nCeux-ci sont partiellement remplis de marqueurs au n\u00e9on.  <\/p>\n<p><strong>Donn\u00e9es techniques :<\/strong><\/p>\n<\/p>\n<p>Il s&rsquo;agit de deux pi\u00e8ces uniques en technique mixte.<\/p>\n<p>Les motifs sont des drones de toutes sortes. Des impressions au pochoir noir et blanc, des aquarelles et des dessins libres au crayon noir sont appliqu\u00e9s sur ce calque.<br \/>\nLes couleurs et les pigments sont li\u00e9s \u00e0 l&rsquo;eau et neutres pour le climat. <\/p>\n<p>Impression au pochoir et dessin libre en noir, blanc et couleur fluo.<\/p>\n<p>29 x 21 cm, format vertical, longueur totale 722 cm, 24 pages, travaill\u00e9 sur une seule face.<\/p>\n<p>Les deux couvertures ext\u00e9rieures sont en carton noir imprim\u00e9.<\/p>\n<p>Les peintures et les pigments sont li\u00e9s \u00e0 l&rsquo;eau et neutres pour le climat.<\/p>\n<p>Le carton de 200 gr.<br \/>\nLe carton \u00e0 dessin est sans acide.<br \/>\nLieu de cr\u00e9ation : Berlin.<br \/>\n2024   <\/p>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"tab-pane elementkit-tab-pane elementor-repeater-item-190a405 \" id=\"content-190a4056a980fc1d088f\" role=\"tabpanel\"\n                         aria-labelledby=\"content-190a4056a980fc1d088f-tab\" tabindex=\"0\">\n                        <div class=\"animated fadeIn\">\n                            ngg_shortcode_0_placeholder\n                        <\/div>\n                    <\/div>\n                \n            <\/div>\n                    <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ca82c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ca82c0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a27cc9d\" data-id=\"a27cc9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Info Images (n\u00e9on)couleurs dans le ciel Dans ce travail en deux parties, j&#8217;aborde les nombreux \u00e9v\u00e9nements simultan\u00e9s et ambigus de cette \u00e9poque dystopique. J&#8217;ai du mal \u00e0 en croire mes yeux. Qu&#8217;est-ce qui est r\u00e9alit\u00e9, v\u00e9rit\u00e9, belles apparences ou ab\u00eeme de cruaut\u00e9 ? Des drones militaires, d\u00e9guis\u00e9s en animaux tels que des hiboux ou des [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18701,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[212,221,214],"tags":[],"class_list":["post-18698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art_projects-fr","category-livres-et-leporellos","category-paperworks-linolprints-fr"],"_links":{"self":[{"href":"https:\/\/nele-stroebel.de\/fr\/wp-json\/wp\/v2\/posts\/18698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nele-stroebel.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nele-stroebel.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nele-stroebel.de\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/nele-stroebel.de\/fr\/wp-json\/wp\/v2\/comments?post=18698"}],"version-history":[{"count":4,"href":"https:\/\/nele-stroebel.de\/fr\/wp-json\/wp\/v2\/posts\/18698\/revisions"}],"predecessor-version":[{"id":18743,"href":"https:\/\/nele-stroebel.de\/fr\/wp-json\/wp\/v2\/posts\/18698\/revisions\/18743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nele-stroebel.de\/fr\/wp-json\/wp\/v2\/media\/18701"}],"wp:attachment":[{"href":"https:\/\/nele-stroebel.de\/fr\/wp-json\/wp\/v2\/media?parent=18698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nele-stroebel.de\/fr\/wp-json\/wp\/v2\/categories?post=18698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nele-stroebel.de\/fr\/wp-json\/wp\/v2\/tags?post=18698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}